{"id":208,"count":8,"description":"","link":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/","name":"Noticias","slug":"noticias","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Noticias archivos - Espelt Viticultores<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de Noticias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Espelt Viticultores\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/espelt_opengraph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CellerEspelt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/categoria-es\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/categoria-es\\\/noticias\\\/\",\"name\":\"Noticias archivos - Espelt Viticultores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/categoria-es\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/categoria-es\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/tienda-espelt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"name\":\"Espelt Viticultores\",\"description\":\"Vinos del Empord\u00e0 i enoturismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\",\"name\":\"Espelt Viticultors - tienda online\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"contentUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"width\":818,\"height\":272,\"caption\":\"Espelt Viticultors - tienda online\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espelt.viticultors\",\"https:\\\/\\\/x.com\\\/CellerEspelt\",\"https:\\\/\\\/www.instagram.com\\\/cellerespelt\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Noticias archivos - Espelt Viticultores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de Noticias","og_url":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/","og_site_name":"Espelt Viticultores","og_image":[{"width":837,"height":837,"url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/espelt_opengraph.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CellerEspelt","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/","url":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/","name":"Noticias archivos - Espelt Viticultores","isPartOf":{"@id":"https:\/\/espeltviticultors.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/espeltviticultors.com\/es\/categoria-es\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espeltviticultors.com\/es\/tienda-espelt\/"},{"@type":"ListItem","position":2,"name":"Noticias"}]},{"@type":"WebSite","@id":"https:\/\/espeltviticultors.com\/es\/#website","url":"https:\/\/espeltviticultors.com\/es\/","name":"Espelt Viticultores","description":"Vinos del Empord\u00e0 i enoturismo","publisher":{"@id":"https:\/\/espeltviticultors.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espeltviticultors.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/espeltviticultors.com\/es\/#organization","name":"Espelt Viticultors - tienda online","url":"https:\/\/espeltviticultors.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","contentUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","width":818,"height":272,"caption":"Espelt Viticultors - tienda online"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espelt.viticultors","https:\/\/x.com\/CellerEspelt","https:\/\/www.instagram.com\/cellerespelt\/"]}]}},"_links":{"self":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/categories\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts?categories=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}