{"id":4831,"date":"2021-11-12T16:10:43","date_gmt":"2021-11-12T15:10:43","guid":{"rendered":"https:\/\/espeltviticultors.com\/infinits-lots-de-nadal-espelt\/"},"modified":"2022-10-25T12:48:46","modified_gmt":"2022-10-25T10:48:46","slug":"infinits-lots-de-nadal-espelt","status":"publish","type":"post","link":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/","title":{"rendered":"Infinitos lotes de Navidad Espelt"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-demana-el-teu-lot-de-nadal-espelt-a-mida-tenim-una-amplia-gamma-de-vins-escumosos-i-caixes-i-estoigs-estarem-encantats-de-fer-te-arribar-tot-el-nostre-cataleg-de-possibilitats\">Pide tu lote de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches. Estaremos encantados de enviarte todo nuestro cat\u00e1logo de posibilidades.<\/h2>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-1024x768.jpg\" alt=\"Regala Vinos 50\" class=\"wp-image-4892\" srcset=\"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-1024x768.jpg 1024w, https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-300x225.jpg 300w, https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-768x576.jpg 768w, https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-1536x1153.jpg 1536w, https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004-600x450.jpg 600w, https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/04\/IMG-20201105-WA0004.jpg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Estamos encantados un a\u00f1o m\u00e1s de poder ofreceros un trocito de nuestro paisaje, del Empord\u00e0, en tu mesa, en tus regalos. Los lotes de Navidad Espelt son una muy buena opci\u00f3n para tu empresa, grupo de amigos, familias a las que les guste el vino hecho aqu\u00ed.&#13;\n&#13;\nTenemos una amplia variedad de estuches y cajas, diferentes colores y gamas, que podemos combinar como m\u00e1s te gusten. Tambi\u00e9n podemos ayudarte a pensar un complemento con vales regalo en vino o con alguna de nuestras actividades de enoturismo: paseos entre vi\u00f1edos, un fin de semana en Mas Espelt bajo la luz de las estrellas.&#13;\n&#13;\nCualquier cosa que necesites, estamos a tu disposi\u00f3n. Estaremos encantados de ofrecerte estos lotes de Navidad Espelt y todo lo que quieras a\u00f1adir! Escr\u00edbenos y te lo explicamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pide tu lote de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches. Estaremos encantados de enviarte todo nuestro cat\u00e1logo de posibilidades. Estamos encantados un a\u00f1o m\u00e1s de poder ofreceros un trocito de nuestro paisaje, del Empord\u00e0, en tu mesa, en tus regalos. Los lotes de Navidad Espelt son [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[207],"tags":[271],"class_list":["post-4831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gastronomia-es","tag-regals-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Infinitos lotes de Navidad Espelt -<\/title>\n<meta name=\"description\" content=\"Lotes de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infinitos lotes de Navidad Espelt\" \/>\n<meta property=\"og:description\" content=\"Pide tu lote de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches. Estaremos encantados de enviarte todo nuestro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/\" \/>\n<meta property=\"og:site_name\" content=\"Espelt Viticultores\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/espelt.viticultors\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T15:10:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T10:48:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"679\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina Planella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CellerEspelt\" \/>\n<meta name=\"twitter:site\" content=\"@CellerEspelt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Planella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/\"},\"author\":{\"name\":\"Marina Planella\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/person\\\/5f5c9de012090df361fdb0b0040a15e1\"},\"headline\":\"Infinitos lotes de Navidad Espelt\",\"datePublished\":\"2021-11-12T15:10:43+00:00\",\"dateModified\":\"2022-10-25T10:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/terres-negres-espelt.jpg\",\"keywords\":[\"regals\"],\"articleSection\":[\"Gastronom\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/\",\"name\":\"Infinitos lotes de Navidad Espelt -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/terres-negres-espelt.jpg\",\"datePublished\":\"2021-11-12T15:10:43+00:00\",\"dateModified\":\"2022-10-25T10:48:46+00:00\",\"description\":\"Lotes de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/terres-negres-espelt.jpg\",\"contentUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/terres-negres-espelt.jpg\",\"width\":679,\"height\":420,\"caption\":\"terres negres espelt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/infinits-lots-de-nadal-espelt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/tienda-espelt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infinitos lotes de Navidad Espelt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"name\":\"Espelt Viticultores\",\"description\":\"Vinos del Empord\u00e0 i enoturismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\",\"name\":\"Espelt Viticultors - tienda online\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"contentUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"width\":818,\"height\":272,\"caption\":\"Espelt Viticultors - tienda online\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espelt.viticultors\",\"https:\\\/\\\/x.com\\\/CellerEspelt\",\"https:\\\/\\\/www.instagram.com\\\/cellerespelt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/person\\\/5f5c9de012090df361fdb0b0040a15e1\",\"name\":\"Marina Planella\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Infinitos lotes de Navidad Espelt -","description":"Lotes de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/","og_locale":"es_ES","og_type":"article","og_title":"Infinitos lotes de Navidad Espelt","og_description":"Pide tu lote de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches. Estaremos encantados de enviarte todo nuestro","og_url":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/","og_site_name":"Espelt Viticultores","article_publisher":"https:\/\/www.facebook.com\/espelt.viticultors","article_published_time":"2021-11-12T15:10:43+00:00","article_modified_time":"2022-10-25T10:48:46+00:00","og_image":[{"width":679,"height":420,"url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg","type":"image\/jpeg"}],"author":"Marina Planella","twitter_card":"summary_large_image","twitter_creator":"@CellerEspelt","twitter_site":"@CellerEspelt","twitter_misc":{"Escrito por":"Marina Planella","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#article","isPartOf":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/"},"author":{"name":"Marina Planella","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/person\/5f5c9de012090df361fdb0b0040a15e1"},"headline":"Infinitos lotes de Navidad Espelt","datePublished":"2021-11-12T15:10:43+00:00","dateModified":"2022-10-25T10:48:46+00:00","mainEntityOfPage":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/"},"wordCount":173,"publisher":{"@id":"https:\/\/espeltviticultors.com\/es\/#organization"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#primaryimage"},"thumbnailUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg","keywords":["regals"],"articleSection":["Gastronom\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/","url":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/","name":"Infinitos lotes de Navidad Espelt -","isPartOf":{"@id":"https:\/\/espeltviticultors.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#primaryimage"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#primaryimage"},"thumbnailUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg","datePublished":"2021-11-12T15:10:43+00:00","dateModified":"2022-10-25T10:48:46+00:00","description":"Lotes de Navidad Espelt a medida. Tenemos una amplia gama de vinos, espumosos y cajas y estuches.","breadcrumb":{"@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#primaryimage","url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg","contentUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/11\/terres-negres-espelt.jpg","width":679,"height":420,"caption":"terres negres espelt"},{"@type":"BreadcrumbList","@id":"https:\/\/espeltviticultors.com\/es\/infinits-lots-de-nadal-espelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espeltviticultors.com\/es\/tienda-espelt\/"},{"@type":"ListItem","position":2,"name":"Infinitos lotes de Navidad Espelt"}]},{"@type":"WebSite","@id":"https:\/\/espeltviticultors.com\/es\/#website","url":"https:\/\/espeltviticultors.com\/es\/","name":"Espelt Viticultores","description":"Vinos del Empord\u00e0 i enoturismo","publisher":{"@id":"https:\/\/espeltviticultors.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espeltviticultors.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/espeltviticultors.com\/es\/#organization","name":"Espelt Viticultors - tienda online","url":"https:\/\/espeltviticultors.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","contentUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","width":818,"height":272,"caption":"Espelt Viticultors - tienda online"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espelt.viticultors","https:\/\/x.com\/CellerEspelt","https:\/\/www.instagram.com\/cellerespelt\/"]},{"@type":"Person","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/person\/5f5c9de012090df361fdb0b0040a15e1","name":"Marina Planella"}]}},"_links":{"self":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/4831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/comments?post=4831"}],"version-history":[{"count":5,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/4831\/revisions"}],"predecessor-version":[{"id":6676,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/4831\/revisions\/6676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/media\/5956"}],"wp:attachment":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/media?parent=4831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/categories?post=4831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/tags?post=4831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}