{"id":5210,"date":"2022-03-10T14:56:44","date_gmt":"2022-03-10T13:56:44","guid":{"rendered":"https:\/\/espeltviticultors.com\/?p=5210"},"modified":"2023-08-30T09:51:33","modified_gmt":"2023-08-30T07:51:33","slug":"montse-capel-presenta-mynameismoon","status":"publish","type":"post","link":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/","title":{"rendered":"Montse Capel presenta mynameismoon"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-montse-capel-presenta-l-exposicio-mynameismoon-al-celler-espelt-del-19-de-marc-al-29-de-maig-la-mostra-reuneix-14-autoretrats-en-blanc-i-negre-que-l-artista-va-comencar-a-realitzar-el-2014-i-que-culmina-el-2020-durant-el-confinament-de-la-covid-19\">Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. La muestra re\u00fane a 14 autorretratos en blanco y negro que el artista empez\u00f3 a realizar en el 2014 y que culmina en el 2020, durante el confinamiento de la Covid-19.<\/h2>\n\n<p class=\"wp-block-paragraph\">Las fotograf\u00edas de <a href=\"http:\/\/montsecapel.com\/\" target=\"_blank\" rel=\"noopener\">Montse Capel<\/a>, artista ampurdanesa formada en dise\u00f1o de moda y fotograf\u00eda, se mueven entre la intimidad y el misterio, entre la sensualidad y la nostalgia. Precisamente esta mezcla hipn\u00f3tica es la que encontrar\u00e1 si viene a la inauguraci\u00f3n de la exposici\u00f3n mynameismoon que tendr\u00e1 lugar el s\u00e1bado 19 de marzo a las 12 h.<\/p>\n\n<p class=\"wp-block-paragraph\">Durante dos meses tendremos expuesta a estos autorretratos que documentan la relaci\u00f3n sensible entre la soledad y el deseo, una relaci\u00f3n que pas\u00f3 por momentos delicados los d\u00edas que pasamos encerrados en casa. Esta aproximaci\u00f3n \u00edntima del artista a situaciones propias nos evoca con sensibilidad la nostalgia por lo ocurrido, y tambi\u00e9n con el misterio, un ambiente provocador, sensual.&#13;\n&#13;\nMontse Capel busca con su trabajo de fotograf\u00edas \u00edntimas en blanco y negro a un espectador c\u00f3mplice, a trav\u00e9s de las redes sociales o ahora en exposiciones como esta. La inauguraci\u00f3n de mynameismoon tendr\u00e1 lugar en el Celler Espelt el 19 de marzo a las 12 h, intervendr\u00e1 el artista, y tambi\u00e9n Rafa Camps, comisario del ciclo de exposiciones del Celler Espelt, y Anna Espelt, directora de Espelt Viticultors. Se ofrecer\u00e1 una copa de vino a todos los asistentes. \u00a1<a href=\"https:\/\/espeltviticultors.com\/es\/contacto\/\" target=\"_blank\" rel=\"noopener\">Os esperamos<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. La muestra re\u00fane a 14 autorretratos en blanco y negro que el artista empez\u00f3 a realizar en el 2014 y que culmina en el 2020, durante el confinamiento de la Covid-19. Las fotograf\u00edas de Montse Capel, artista ampurdanesa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[206],"tags":[],"class_list":["post-5210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espelt-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Montse Capel presenta mynameismoon -<\/title>\n<meta name=\"description\" content=\"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. Fotograf\u00eda \u00edntima en blanco y negro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montse Capel presenta mynameismoon\" \/>\n<meta property=\"og:description\" content=\"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. La muestra re\u00fane a 14 autorretratos en blanco y negro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/\" \/>\n<meta property=\"og:site_name\" content=\"Espelt Viticultores\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/espelt.viticultors\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T13:56:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T07:51:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina Planella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CellerEspelt\" \/>\n<meta name=\"twitter:site\" content=\"@CellerEspelt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina Planella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/\"},\"author\":{\"name\":\"Marina Planella\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/person\\\/5f5c9de012090df361fdb0b0040a15e1\"},\"headline\":\"Montse Capel presenta mynameismoon\",\"datePublished\":\"2022-03-10T13:56:44+00:00\",\"dateModified\":\"2023-08-30T07:51:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LaEscalera_montsecapel-680.jpg\",\"articleSection\":[\"Espelt Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/\",\"name\":\"Montse Capel presenta mynameismoon -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LaEscalera_montsecapel-680.jpg\",\"datePublished\":\"2022-03-10T13:56:44+00:00\",\"dateModified\":\"2023-08-30T07:51:33+00:00\",\"description\":\"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. Fotograf\u00eda \u00edntima en blanco y negro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LaEscalera_montsecapel-680.jpg\",\"contentUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/LaEscalera_montsecapel-680.jpg\",\"width\":680,\"height\":420,\"caption\":\"Montse capel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/montse-capel-presenta-mynameismoon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/tienda-espelt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montse Capel presenta mynameismoon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"name\":\"Espelt Viticultores\",\"description\":\"Vinos del Empord\u00e0 i enoturismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#organization\",\"name\":\"Espelt Viticultors - tienda online\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"contentUrl\":\"https:\\\/\\\/espeltviticultors.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo_color_trasparent.png\",\"width\":818,\"height\":272,\"caption\":\"Espelt Viticultors - tienda online\"},\"image\":{\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/espelt.viticultors\",\"https:\\\/\\\/x.com\\\/CellerEspelt\",\"https:\\\/\\\/www.instagram.com\\\/cellerespelt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espeltviticultors.com\\\/es\\\/#\\\/schema\\\/person\\\/5f5c9de012090df361fdb0b0040a15e1\",\"name\":\"Marina Planella\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Montse Capel presenta mynameismoon -","description":"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. Fotograf\u00eda \u00edntima en blanco y negro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/","og_locale":"es_ES","og_type":"article","og_title":"Montse Capel presenta mynameismoon","og_description":"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. La muestra re\u00fane a 14 autorretratos en blanco y negro","og_url":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/","og_site_name":"Espelt Viticultores","article_publisher":"https:\/\/www.facebook.com\/espelt.viticultors","article_published_time":"2022-03-10T13:56:44+00:00","article_modified_time":"2023-08-30T07:51:33+00:00","og_image":[{"width":680,"height":420,"url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg","type":"image\/jpeg"}],"author":"Marina Planella","twitter_card":"summary_large_image","twitter_creator":"@CellerEspelt","twitter_site":"@CellerEspelt","twitter_misc":{"Escrito por":"Marina Planella","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#article","isPartOf":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/"},"author":{"name":"Marina Planella","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/person\/5f5c9de012090df361fdb0b0040a15e1"},"headline":"Montse Capel presenta mynameismoon","datePublished":"2022-03-10T13:56:44+00:00","dateModified":"2023-08-30T07:51:33+00:00","mainEntityOfPage":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/"},"wordCount":259,"publisher":{"@id":"https:\/\/espeltviticultors.com\/es\/#organization"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#primaryimage"},"thumbnailUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg","articleSection":["Espelt Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/","url":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/","name":"Montse Capel presenta mynameismoon -","isPartOf":{"@id":"https:\/\/espeltviticultors.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#primaryimage"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#primaryimage"},"thumbnailUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg","datePublished":"2022-03-10T13:56:44+00:00","dateModified":"2023-08-30T07:51:33+00:00","description":"Montse Capel presenta la exposici\u00f3n mynameismoon en Celler Espelt, del 19 de marzo al 29 de mayo. Fotograf\u00eda \u00edntima en blanco y negro.","breadcrumb":{"@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#primaryimage","url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg","contentUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2022\/03\/LaEscalera_montsecapel-680.jpg","width":680,"height":420,"caption":"Montse capel"},{"@type":"BreadcrumbList","@id":"https:\/\/espeltviticultors.com\/es\/montse-capel-presenta-mynameismoon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espeltviticultors.com\/es\/tienda-espelt\/"},{"@type":"ListItem","position":2,"name":"Montse Capel presenta mynameismoon"}]},{"@type":"WebSite","@id":"https:\/\/espeltviticultors.com\/es\/#website","url":"https:\/\/espeltviticultors.com\/es\/","name":"Espelt Viticultores","description":"Vinos del Empord\u00e0 i enoturismo","publisher":{"@id":"https:\/\/espeltviticultors.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espeltviticultors.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/espeltviticultors.com\/es\/#organization","name":"Espelt Viticultors - tienda online","url":"https:\/\/espeltviticultors.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","contentUrl":"https:\/\/espeltviticultors.com\/wp-content\/uploads\/2021\/02\/logo_color_trasparent.png","width":818,"height":272,"caption":"Espelt Viticultors - tienda online"},"image":{"@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/espelt.viticultors","https:\/\/x.com\/CellerEspelt","https:\/\/www.instagram.com\/cellerespelt\/"]},{"@type":"Person","@id":"https:\/\/espeltviticultors.com\/es\/#\/schema\/person\/5f5c9de012090df361fdb0b0040a15e1","name":"Marina Planella"}]}},"_links":{"self":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/5210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/comments?post=5210"}],"version-history":[{"count":5,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/5210\/revisions"}],"predecessor-version":[{"id":7355,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/posts\/5210\/revisions\/7355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/media\/5207"}],"wp:attachment":[{"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/media?parent=5210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/categories?post=5210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espeltviticultors.com\/es\/wp-json\/wp\/v2\/tags?post=5210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}